{"id":5457,"date":"2019-10-21T17:19:01","date_gmt":"2019-10-21T15:19:01","guid":{"rendered":"https:\/\/www.kantner-partner.de\/?p=5457"},"modified":"2019-11-29T18:03:28","modified_gmt":"2019-11-29T17:03:28","slug":"bayoblg-kein-anspruch-auf-ueberbau-bei-waermedaemmung","status":"publish","type":"post","link":"https:\/\/www.kantner-partner.de\/en\/bayoblg-kein-anspruch-auf-ueberbau-bei-waermedaemmung","title":{"rendered":"BayObLG: Kein Anspruch auf \u00dcberbau bei W\u00e4rmed\u00e4mmung"},"content":{"rendered":"<p style=\"text-align: justify;\">Nach Auffassung des Obersten Bayerischen Landesgerichts (BayObLG) muss ein Grundst\u00fcckseigent\u00fcmer einen \u00dcberbau eines Nachbargrundst\u00fccks mit W\u00e4rmed\u00e4mmung (WDVS) nicht dulden, wenn eine alternativ in Betracht kommende Ausf\u00fchrung als Innend\u00e4mmung mit vertretbarem Aufwand appliziert werden kann &#8211; BayObLG, Urteil vom 01. Oktober 2019 &#8211; 1 ZRR 4\/19.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nach Auffassung des Obersten Bayerischen Landesgerichts (BayObLG) muss ein Grundst\u00fcckseigent\u00fcmer einen \u00dcberbau eines Nachbargrundst\u00fccks mit W\u00e4rmed\u00e4mmung (WDVS) nicht dulden, wenn eine alternativ in Betracht kommende Ausf\u00fchrung als Innend\u00e4mmung mit vertretbarem <a class=\"moretag\" href=\"https:\/\/www.kantner-partner.de\/en\/bayoblg-kein-anspruch-auf-ueberbau-bei-waermedaemmung\">read more&#8230;<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[383,20,40],"tags":[491,489,100,41],"class_list":["post-5457","post","type-post","status-publish","format-standard","hentry","category-aktuelles","category-immobilienbewertung","category-rechtsprechung","tag-rechtsprechung","tag-ueberbau","tag-waermedaemmung","tag-wdvs"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BayObLG: Kein Anspruch auf \u00dcberbau bei W\u00e4rmed\u00e4mmung - Bausachverst\u00e4ndiger I Immobiliengutachter I M\u00fcnchen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kantner-partner.de\/bayoblg-kein-anspruch-auf-ueberbau-bei-waermedaemmung\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BayObLG: Kein Anspruch auf \u00dcberbau bei W\u00e4rmed\u00e4mmung - Bausachverst\u00e4ndiger I Immobiliengutachter I M\u00fcnchen\" \/>\n<meta property=\"og:description\" content=\"Nach Auffassung des Obersten Bayerischen Landesgerichts (BayObLG) muss ein Grundst\u00fcckseigent\u00fcmer einen \u00dcberbau eines Nachbargrundst\u00fccks mit W\u00e4rmed\u00e4mmung (WDVS) nicht dulden, wenn eine alternativ in Betracht kommende Ausf\u00fchrung als Innend\u00e4mmung mit vertretbarem read more...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kantner-partner.de\/bayoblg-kein-anspruch-auf-ueberbau-bei-waermedaemmung\" \/>\n<meta property=\"og:site_name\" content=\"Bausachverst\u00e4ndiger I Immobiliengutachter I M\u00fcnchen\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kantner.partner\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-21T15:19:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-29T17:03:28+00:00\" \/>\n<meta name=\"author\" content=\"Kantner\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@KP_Info\" \/>\n<meta name=\"twitter:site\" content=\"@KP_Info\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Kantner\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.kantner-partner.de\\\/bayoblg-kein-anspruch-auf-ueberbau-bei-waermedaemmung#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kantner-partner.de\\\/bayoblg-kein-anspruch-auf-ueberbau-bei-waermedaemmung\"},\"author\":{\"name\":\"Kantner\",\"@id\":\"https:\\\/\\\/www.kantner-partner.de\\\/#\\\/schema\\\/person\\\/941214ca61f08add6a1d63f6f22e83a4\"},\"headline\":\"BayObLG: Kein Anspruch auf \u00dcberbau bei W\u00e4rmed\u00e4mmung\",\"datePublished\":\"2019-10-21T15:19:01+00:00\",\"dateModified\":\"2019-11-29T17:03:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.kantner-partner.de\\\/bayoblg-kein-anspruch-auf-ueberbau-bei-waermedaemmung\"},\"wordCount\":57,\"keywords\":[\"Rechtsprechung\",\"\u00dcberbau\",\"W\u00e4rmed\u00e4mmung\",\"WDVS\"],\"articleSection\":[\"Aktuelles\",\"Immobilienbewertung\",\"Rechtsprechung\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kantner-partner.de\\\/bayoblg-kein-anspruch-auf-ueberbau-bei-waermedaemmung\",\"url\":\"https:\\\/\\\/www.kantner-partner.de\\\/bayoblg-kein-anspruch-auf-ueberbau-bei-waermedaemmung\",\"name\":\"BayObLG: Kein Anspruch auf \u00dcberbau bei W\u00e4rmed\u00e4mmung - Bausachverst\u00e4ndiger I Immobiliengutachter I M\u00fcnchen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kantner-partner.de\\\/#website\"},\"datePublished\":\"2019-10-21T15:19:01+00:00\",\"dateModified\":\"2019-11-29T17:03:28+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.kantner-partner.de\\\/#\\\/schema\\\/person\\\/941214ca61f08add6a1d63f6f22e83a4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kantner-partner.de\\\/bayoblg-kein-anspruch-auf-ueberbau-bei-waermedaemmung#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kantner-partner.de\\\/bayoblg-kein-anspruch-auf-ueberbau-bei-waermedaemmung\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kantner-partner.de\\\/bayoblg-kein-anspruch-auf-ueberbau-bei-waermedaemmung#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.kantner-partner.de\\\/en\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BayObLG: Kein Anspruch auf \u00dcberbau bei W\u00e4rmed\u00e4mmung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kantner-partner.de\\\/#website\",\"url\":\"https:\\\/\\\/www.kantner-partner.de\\\/\",\"name\":\"Bausachverst\u00e4ndiger I Immobiliengutachter I M\u00fcnchen\",\"description\":\"SV f\u00fcr Wertermittlung, Bauwerksabdichtung, Betoninstandsetzung, Schimmelpilz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kantner-partner.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.kantner-partner.de\\\/#\\\/schema\\\/person\\\/941214ca61f08add6a1d63f6f22e83a4\",\"name\":\"Kantner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/56e0fcbea0ae76dec44e883c6fc42e745b1ae707017419c4d7dec182bae5f380?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/56e0fcbea0ae76dec44e883c6fc42e745b1ae707017419c4d7dec182bae5f380?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/56e0fcbea0ae76dec44e883c6fc42e745b1ae707017419c4d7dec182bae5f380?s=96&d=mm&r=g\",\"caption\":\"Kantner\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BayObLG: Kein Anspruch auf \u00dcberbau bei W\u00e4rmed\u00e4mmung - Bausachverst\u00e4ndiger I Immobiliengutachter I M\u00fcnchen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kantner-partner.de\/bayoblg-kein-anspruch-auf-ueberbau-bei-waermedaemmung","og_locale":"en_US","og_type":"article","og_title":"BayObLG: Kein Anspruch auf \u00dcberbau bei W\u00e4rmed\u00e4mmung - Bausachverst\u00e4ndiger I Immobiliengutachter I M\u00fcnchen","og_description":"Nach Auffassung des Obersten Bayerischen Landesgerichts (BayObLG) muss ein Grundst\u00fcckseigent\u00fcmer einen \u00dcberbau eines Nachbargrundst\u00fccks mit W\u00e4rmed\u00e4mmung (WDVS) nicht dulden, wenn eine alternativ in Betracht kommende Ausf\u00fchrung als Innend\u00e4mmung mit vertretbarem read more...","og_url":"https:\/\/www.kantner-partner.de\/bayoblg-kein-anspruch-auf-ueberbau-bei-waermedaemmung","og_site_name":"Bausachverst\u00e4ndiger I Immobiliengutachter I M\u00fcnchen","article_publisher":"https:\/\/www.facebook.com\/kantner.partner","article_published_time":"2019-10-21T15:19:01+00:00","article_modified_time":"2019-11-29T17:03:28+00:00","author":"Kantner","twitter_card":"summary_large_image","twitter_creator":"@KP_Info","twitter_site":"@KP_Info","twitter_misc":{"Written by":"Kantner"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.kantner-partner.de\/bayoblg-kein-anspruch-auf-ueberbau-bei-waermedaemmung#article","isPartOf":{"@id":"https:\/\/www.kantner-partner.de\/bayoblg-kein-anspruch-auf-ueberbau-bei-waermedaemmung"},"author":{"name":"Kantner","@id":"https:\/\/www.kantner-partner.de\/#\/schema\/person\/941214ca61f08add6a1d63f6f22e83a4"},"headline":"BayObLG: Kein Anspruch auf \u00dcberbau bei W\u00e4rmed\u00e4mmung","datePublished":"2019-10-21T15:19:01+00:00","dateModified":"2019-11-29T17:03:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.kantner-partner.de\/bayoblg-kein-anspruch-auf-ueberbau-bei-waermedaemmung"},"wordCount":57,"keywords":["Rechtsprechung","\u00dcberbau","W\u00e4rmed\u00e4mmung","WDVS"],"articleSection":["Aktuelles","Immobilienbewertung","Rechtsprechung"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.kantner-partner.de\/bayoblg-kein-anspruch-auf-ueberbau-bei-waermedaemmung","url":"https:\/\/www.kantner-partner.de\/bayoblg-kein-anspruch-auf-ueberbau-bei-waermedaemmung","name":"BayObLG: Kein Anspruch auf \u00dcberbau bei W\u00e4rmed\u00e4mmung - Bausachverst\u00e4ndiger I Immobiliengutachter I M\u00fcnchen","isPartOf":{"@id":"https:\/\/www.kantner-partner.de\/#website"},"datePublished":"2019-10-21T15:19:01+00:00","dateModified":"2019-11-29T17:03:28+00:00","author":{"@id":"https:\/\/www.kantner-partner.de\/#\/schema\/person\/941214ca61f08add6a1d63f6f22e83a4"},"breadcrumb":{"@id":"https:\/\/www.kantner-partner.de\/bayoblg-kein-anspruch-auf-ueberbau-bei-waermedaemmung#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kantner-partner.de\/bayoblg-kein-anspruch-auf-ueberbau-bei-waermedaemmung"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.kantner-partner.de\/bayoblg-kein-anspruch-auf-ueberbau-bei-waermedaemmung#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kantner-partner.de\/en"},{"@type":"ListItem","position":2,"name":"BayObLG: Kein Anspruch auf \u00dcberbau bei W\u00e4rmed\u00e4mmung"}]},{"@type":"WebSite","@id":"https:\/\/www.kantner-partner.de\/#website","url":"https:\/\/www.kantner-partner.de\/","name":"Bausachverst\u00e4ndiger I Immobiliengutachter I M\u00fcnchen","description":"SV f\u00fcr Wertermittlung, Bauwerksabdichtung, Betoninstandsetzung, Schimmelpilz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kantner-partner.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.kantner-partner.de\/#\/schema\/person\/941214ca61f08add6a1d63f6f22e83a4","name":"Kantner","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/56e0fcbea0ae76dec44e883c6fc42e745b1ae707017419c4d7dec182bae5f380?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/56e0fcbea0ae76dec44e883c6fc42e745b1ae707017419c4d7dec182bae5f380?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/56e0fcbea0ae76dec44e883c6fc42e745b1ae707017419c4d7dec182bae5f380?s=96&d=mm&r=g","caption":"Kantner"}}]}},"_links":{"self":[{"href":"https:\/\/www.kantner-partner.de\/en\/wp-json\/wp\/v2\/posts\/5457","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kantner-partner.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kantner-partner.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kantner-partner.de\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kantner-partner.de\/en\/wp-json\/wp\/v2\/comments?post=5457"}],"version-history":[{"count":2,"href":"https:\/\/www.kantner-partner.de\/en\/wp-json\/wp\/v2\/posts\/5457\/revisions"}],"predecessor-version":[{"id":5468,"href":"https:\/\/www.kantner-partner.de\/en\/wp-json\/wp\/v2\/posts\/5457\/revisions\/5468"}],"wp:attachment":[{"href":"https:\/\/www.kantner-partner.de\/en\/wp-json\/wp\/v2\/media?parent=5457"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kantner-partner.de\/en\/wp-json\/wp\/v2\/categories?post=5457"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kantner-partner.de\/en\/wp-json\/wp\/v2\/tags?post=5457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}